{"id":2525,"date":"2024-03-03T05:00:45","date_gmt":"2024-03-03T05:00:45","guid":{"rendered":"https:\/\/thelighthouse-lephare.ca\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/"},"modified":"2025-04-25T18:48:25","modified_gmt":"2025-04-25T18:48:25","slug":"therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape","status":"publish","type":"post","link":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/","title":{"rendered":"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape)"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><img decoding=\"async\" class=\"wp-image-2269 alignright\" src=\"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg\" alt=\"\" width=\"589\" height=\"393\" srcset=\"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-200x133.jpg 200w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-300x200.jpg 300w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-400x267.jpg 400w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-600x400.jpg 600w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-768x512.jpg 768w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-800x533.jpg 800w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-1024x683.jpg 1024w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-1200x800.jpg 1200w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-1536x1024.jpg 1536w, https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg 2560w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><strong>\u00c0 quoi dois-je m&rsquo;attendre lorsque j&rsquo;entame mon parcours th\u00e9rapeutique ?<\/strong><\/p>\n<p>Si vous avez des difficult\u00e9s, que vous pensez avoir besoin d&rsquo;aide et que vous vous demandez \u00e0 quoi vous attendre dans le cadre de votre th\u00e9rapie, les points suivants vous seront utiles. Diff\u00e9rents facteurs peuvent influencer la dur\u00e9e, le rythme de progression et l&rsquo;efficacit\u00e9 globale de votre th\u00e9rapie. Nous allons ici explorer ces facettes en d\u00e9tail, et mettre en lumi\u00e8re la mani\u00e8re dont chacune contribue au processus th\u00e9rapeutique.<\/p>\n<p><strong>Combien de temps dois-je m&rsquo;attendre \u00e0 suivre une th\u00e9rapie ?<\/strong><\/p>\n<p>La dur\u00e9e de la th\u00e9rapie n&rsquo;est pas un concept unique ; c&rsquo;est un aspect nuanc\u00e9 qui varie consid\u00e9rablement en fonction des besoins individuels et des circonstances. Une th\u00e9rapie \u00e0 court terme peut convenir \u00e0 certaines personnes. Il s&rsquo;agit d&rsquo;une approche cibl\u00e9e qui permet d&rsquo;aborder des questions ou des objectifs sp\u00e9cifiques dans le cadre d&rsquo;un nombre limit\u00e9 de s\u00e9ances. Pour d&rsquo;autres, une th\u00e9rapie \u00e0 long terme peut s&rsquo;av\u00e9rer n\u00e9cessaire si vous \u00eates aux prises avec des probl\u00e8mes plus profonds. Il offre plus de temps pour cultiver la perspicacit\u00e9, d\u00e9velopper des m\u00e9canismes d&rsquo;adaptation et favoriser une croissance et une transformation personnelles durables.<\/p>\n<p><strong>\u00c0 quelle fr\u00e9quence dois-je voir mon th\u00e9rapeute ?<\/strong><\/p>\n<p>La fr\u00e9quence des s\u00e9ances de th\u00e9rapie joue un r\u00f4le essentiel dans la d\u00e9termination de la dur\u00e9e totale de la th\u00e9rapie. Pour certains, des s\u00e9ances hebdomadaires sont plus b\u00e9n\u00e9fiques, surtout au d\u00e9but, pour aider \u00e0 stabiliser l&rsquo;humeur et \u00e0 prendre l&rsquo;\u00e9lan du changement. D&rsquo;autres peuvent opter pour des rendez-vous bihebdomadaires ou mensuels. Cette d\u00e9cision d\u00e9pend souvent de plusieurs facteurs, notamment de la gravit\u00e9 des probl\u00e8mes, de votre disponibilit\u00e9 et de consid\u00e9rations financi\u00e8res. En adaptant la fr\u00e9quence des s\u00e9ances \u00e0 vos besoins particuliers, vos <span style=\"text-decoration: line-through;\">th\u00e9rapeutes<\/span> vous aideront \u00e0 optimiser votre parcours th\u00e9rapeutique pour une efficacit\u00e9 maximale.<\/p>\n<p><strong>Comment saurai-je que je m&rsquo;am\u00e9liore ?<\/strong><\/p>\n<p>Votre th\u00e9rapeute travaillera avec vous pour fixer des objectifs et suivre vos progr\u00e8s. Vous gagnerez en profondeur, acquerrez de nouvelles capacit\u00e9s d&rsquo;adaptation et constaterez des changements positifs dans votre vie. Vous serez peut-\u00eatre pr\u00eat \u00e0 ajuster la fr\u00e9quence des s\u00e9ances ou \u00e0 passer \u00e0 une phase d&rsquo;entretien de la th\u00e9rapie.<\/p>\n<p><strong>Que se passe-t-il lorsque je commence \u00e0 me sentir mieux ?<\/strong><\/p>\n<p>Apr\u00e8s avoir atteint les objectifs initiaux de la th\u00e9rapie, vous pouvez choisir de poursuivre la th\u00e9rapie en fonction des besoins pour maintenir les progr\u00e8s et pr\u00e9venir les rechutes. Cette approche proactive peut impliquer des s\u00e9ances de contr\u00f4le p\u00e9riodiques ou la recherche d&rsquo;un soutien th\u00e9rapeutique pendant les p\u00e9riodes de stress accru ou les transitions importantes de la vie. En int\u00e9grant la th\u00e9rapie d&rsquo;entretien dans votre routine de soins personnels, vous pouvez maintenir l&rsquo;\u00e9lan de croissance et de r\u00e9silience que vous avez cultiv\u00e9 au cours de votre parcours th\u00e9rapeutique. Vous et votre th\u00e9rapeute pouvez \u00e9galement d\u00e9cider de faire une pause ou de mettre fin \u00e0 la th\u00e9rapie. Ensemble, vous vous pr\u00e9parerez \u00e0 mettre fin aux services et vous \u00e9laborerez un plan pour rester en bonne sant\u00e9 apr\u00e8s la fin des services. Et bien s\u00fbr, vous \u00eates toujours le bienvenu pour reprendre la th\u00e9rapie au fur et \u00e0 mesure que de nouvelles questions se posent.<\/p>\n<p><strong>Comment savez-vous ce qui va me convenir ?<\/strong><\/p>\n<p>Nous reconnaissons que chaque personne est unique, avec ses propres circonstances. Votre th\u00e9rapeute collaborera avec vous pour cr\u00e9er un plan th\u00e9rapeutique qui s&rsquo;aligne sur vos besoins, vos objectifs, vos pr\u00e9f\u00e9rences et vos ressources. Gr\u00e2ce \u00e0 un dialogue ouvert et \u00e0 une compr\u00e9hension mutuelle, nous vous aiderons \u00e0 trouver le chemin d&rsquo;une meilleure sant\u00e9 mentale.<\/p>\n<p>Votre th\u00e9rapeute vous accompagnera tout au long de votre parcours th\u00e9rapeutique. Ils s&rsquo;engagent \u00e0 assurer votre r\u00e9ussite et souhaitent conna\u00eetre votre avis sur votre processus afin d&rsquo;ajuster leur approche si n\u00e9cessaire. Savoir ce qui fonctionne pour vous et ce qui ne fonctionne pas sera la cl\u00e9 de votre succ\u00e8s ensemble.<\/p>\n<p>Si vous \u00eates pr\u00eat \u00e0 entamer votre voyage, nous serions ravis de vous entendre.<\/p>\n<p>Contactez-nous \u00e0 l&rsquo;adresse suivante<a href=\"mailto:info@thelighthouse-lephare.ca\"> <strong>info@thelighthouse-lephare.ca <\/strong><\/a>aujourd&rsquo;hui.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[29,28,27],"class_list":["post-2525","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","tag-kemptville-fr","tag-psychotherapie","tag-therapie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape) - The Lighthouse<\/title>\n<meta name=\"description\" content=\"Vous vous demandez ce qui vous attend au cours de votre parcours th\u00e9rapeutique ? Nous r\u00e9pondons aux principales questions que se posent les nouveaux clients sur la psychoth\u00e9rapie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape) - The Lighthouse\" \/>\n<meta property=\"og:description\" content=\"Vous vous demandez ce qui vous attend au cours de votre parcours th\u00e9rapeutique ? Nous r\u00e9pondons aux principales questions que se posent les nouveaux clients sur la psychoth\u00e9rapie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"The Lighthouse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thelighthouse.lephare\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-03T05:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T18:48:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#\\\/schema\\\/person\\\/637286fc3644af46371f1fe04163b4a4\"},\"headline\":\"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape)\",\"datePublished\":\"2024-03-03T05:00:45+00:00\",\"dateModified\":\"2025-04-25T18:48:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/\"},\"wordCount\":857,\"publisher\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1898964172-scaled.jpg\",\"keywords\":[\"kemptville\",\"psychoth\u00e9rapie\",\"th\u00e9rapie\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/\",\"url\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/\",\"name\":\"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape) - The Lighthouse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1898964172-scaled.jpg\",\"datePublished\":\"2024-03-03T05:00:45+00:00\",\"dateModified\":\"2025-04-25T18:48:25+00:00\",\"description\":\"Vous vous demandez ce qui vous attend au cours de votre parcours th\u00e9rapeutique ? Nous r\u00e9pondons aux principales questions que se posent les nouveaux clients sur la psychoth\u00e9rapie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1898964172-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1898964172-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#website\",\"url\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/\",\"name\":\"The Lighthouse-Lephare\",\"description\":\"Counselling and Psychotherapy\",\"publisher\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#organization\",\"name\":\"The Lighthouse-Lephare Counselling and Psychotherapy\",\"alternateName\":\"The Lighthouse-Lephare\",\"url\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/thelighthouse.jpg\",\"contentUrl\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/thelighthouse.jpg\",\"width\":1200,\"height\":799,\"caption\":\"The Lighthouse-Lephare Counselling and Psychotherapy\"},\"image\":{\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thelighthouse.lephare\",\"https:\\\/\\\/www.instagram.com\\\/thelighthouselephare\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/#\\\/schema\\\/person\\\/637286fc3644af46371f1fe04163b4a4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5777ed6a22c4a48ed901434f6ae45a771405a67e8eac43b3931300f471cc1a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5777ed6a22c4a48ed901434f6ae45a771405a67e8eac43b3931300f471cc1a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5777ed6a22c4a48ed901434f6ae45a771405a67e8eac43b3931300f471cc1a0?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/thelighthouse-lephare.ca\"],\"url\":\"https:\\\/\\\/thelighthouse-lephare.ca\\\/fr\\\/author\\\/natalie_lpah3kbz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape) - The Lighthouse","description":"Vous vous demandez ce qui vous attend au cours de votre parcours th\u00e9rapeutique ? Nous r\u00e9pondons aux principales questions que se posent les nouveaux clients sur la psychoth\u00e9rapie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape) - The Lighthouse","og_description":"Vous vous demandez ce qui vous attend au cours de votre parcours th\u00e9rapeutique ? Nous r\u00e9pondons aux principales questions que se posent les nouveaux clients sur la psychoth\u00e9rapie.","og_url":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/","og_site_name":"The Lighthouse","article_publisher":"https:\/\/www.facebook.com\/thelighthouse.lephare","article_published_time":"2024-03-03T05:00:45+00:00","article_modified_time":"2025-04-25T18:48:25+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#article","isPartOf":{"@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/"},"author":{"name":"admin","@id":"https:\/\/thelighthouse-lephare.ca\/#\/schema\/person\/637286fc3644af46371f1fe04163b4a4"},"headline":"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape)","datePublished":"2024-03-03T05:00:45+00:00","dateModified":"2025-04-25T18:48:25+00:00","mainEntityOfPage":{"@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/"},"wordCount":857,"publisher":{"@id":"https:\/\/thelighthouse-lephare.ca\/#organization"},"image":{"@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg","keywords":["kemptville","psychoth\u00e9rapie","th\u00e9rapie"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/","url":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/","name":"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape) - The Lighthouse","isPartOf":{"@id":"https:\/\/thelighthouse-lephare.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#primaryimage"},"image":{"@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg","datePublished":"2024-03-03T05:00:45+00:00","dateModified":"2025-04-25T18:48:25+00:00","description":"Vous vous demandez ce qui vous attend au cours de votre parcours th\u00e9rapeutique ? Nous r\u00e9pondons aux principales questions que se posent les nouveaux clients sur la psychoth\u00e9rapie.","breadcrumb":{"@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#primaryimage","url":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg","contentUrl":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/03\/shutterstock_1898964172-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/thelighthouse-lephare.ca\/fr\/therapie-101-ce-que-vous-devez-savoir-nous-vous-accompagnons-a-chaque-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thelighthouse-lephare.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Th\u00e9rapie 101 : Ce que vous devez savoir (Nous vous accompagnons \u00e0 chaque \u00e9tape)"}]},{"@type":"WebSite","@id":"https:\/\/thelighthouse-lephare.ca\/#website","url":"https:\/\/thelighthouse-lephare.ca\/","name":"The Lighthouse-Lephare","description":"Counselling and Psychotherapy","publisher":{"@id":"https:\/\/thelighthouse-lephare.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thelighthouse-lephare.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thelighthouse-lephare.ca\/#organization","name":"The Lighthouse-Lephare Counselling and Psychotherapy","alternateName":"The Lighthouse-Lephare","url":"https:\/\/thelighthouse-lephare.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thelighthouse-lephare.ca\/#\/schema\/logo\/image\/","url":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/01\/thelighthouse.jpg","contentUrl":"https:\/\/thelighthouse-lephare.ca\/wp-content\/uploads\/2024\/01\/thelighthouse.jpg","width":1200,"height":799,"caption":"The Lighthouse-Lephare Counselling and Psychotherapy"},"image":{"@id":"https:\/\/thelighthouse-lephare.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thelighthouse.lephare","https:\/\/www.instagram.com\/thelighthouselephare\/"]},{"@type":"Person","@id":"https:\/\/thelighthouse-lephare.ca\/#\/schema\/person\/637286fc3644af46371f1fe04163b4a4","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5777ed6a22c4a48ed901434f6ae45a771405a67e8eac43b3931300f471cc1a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5777ed6a22c4a48ed901434f6ae45a771405a67e8eac43b3931300f471cc1a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5777ed6a22c4a48ed901434f6ae45a771405a67e8eac43b3931300f471cc1a0?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/thelighthouse-lephare.ca"],"url":"https:\/\/thelighthouse-lephare.ca\/fr\/author\/natalie_lpah3kbz\/"}]}},"_links":{"self":[{"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/posts\/2525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/comments?post=2525"}],"version-history":[{"count":10,"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/posts\/2525\/revisions"}],"predecessor-version":[{"id":2651,"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/posts\/2525\/revisions\/2651"}],"wp:attachment":[{"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/media?parent=2525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/categories?post=2525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thelighthouse-lephare.ca\/fr\/wp-json\/wp\/v2\/tags?post=2525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}